{"id":6050,"date":"2024-01-14T08:00:00","date_gmt":"2024-01-14T12:00:00","guid":{"rendered":"https:\/\/www.focolaresciudadnueva.com\/?p=6050"},"modified":"2024-01-10T15:14:07","modified_gmt":"2024-01-10T19:14:07","slug":"senales-de-fraternidad-en-america-latina","status":"publish","type":"post","link":"https:\/\/www.focolaresciudadnueva.com\/inicio\/senales-de-fraternidad-en-america-latina\/","title":{"rendered":"Se\u00f1ales de fraternidad en Am\u00e9rica Latina"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los pueblos Latinoamericanos tenemos la oportunidad de crear fraternidad con nuestros hermanos de Medio Oriente, es una posibilidad que nos ayuda a estar m\u00e1s all\u00e1 de la parte de uno o de otro sino de acoger a todos. Por las migraciones, por la vida de las distintas comunidades presentes en los pa\u00edses se han creado momentos de vivenciar la fe juntos, de celebraciones, de encuentro, de arte vivida por parte de ambos. Se\u00f1ales de hermandad y modos concretos de expresar en nuestras diferencias nuestras creencias religiosas superadoras de nuestra fragilidad y deseo profundo de paz.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"695\" height=\"761\" src=\"https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/SenalesFraternidad1.png\" alt=\"\" class=\"wp-image-6051\" srcset=\"https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/SenalesFraternidad1.png 695w, https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/SenalesFraternidad1-274x300.png 274w, https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/SenalesFraternidad1-580x635.png 580w\" sizes=\"(max-width: 695px) 100vw, 695px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Shabaton, Mariapolis L\u00eda, 2023. Cuando el mundo est\u00e1 roto de odio, de desolaci\u00f3n y guerra nosotros probamos traer algo de luz a tanta oscuridad. Tres religiones conviviendo tiempos sagrados y compartiendo la vida misma. Y \u00a1Es posible! Con respeto, sinceridad, paciencia y voluntad. Gracias por este par\u00e9ntesis de humanidad que renueva nuestras fuerzas para seguir adelante.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"703\" height=\"652\" src=\"https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/SenalesFraternidad2.png\" alt=\"\" class=\"wp-image-6052\" srcset=\"https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/SenalesFraternidad2.png 703w, https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/SenalesFraternidad2-300x278.png 300w, https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/SenalesFraternidad2-580x538.png 580w\" sizes=\"(max-width: 703px) 100vw, 703px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"637\" height=\"227\" src=\"https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/SenalesFraternidad3.png\" alt=\"\" class=\"wp-image-6053\" style=\"width:797px;height:auto\" srcset=\"https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/SenalesFraternidad3.png 637w, https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/SenalesFraternidad3-300x107.png 300w, https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/SenalesFraternidad3-580x207.png 580w\" sizes=\"(max-width: 637px) 100vw, 637px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Los pueblos Latinoamericanos tenemos la oportunidad de crear fraternidad con nuestros hermanos de Medio Oriente, es una posibilidad que nos ayuda a estar m\u00e1s all\u00e1 de la parte de uno o de otro sino de acoger a todos.  <a href=\"https:\/\/www.focolaresciudadnueva.com\/inicio\/senales-de-fraternidad-en-america-latina\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Se\u00f1ales de fraternidad en Am\u00e9rica Latina<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":6054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60,102],"tags":[],"class_list":["post-6050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dialogos-en-la-cultura","category-fraternidad"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/ShabatonMariapolisLia-150x150.png",150,150,true],"cvmm-medium":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/ShabatonMariapolisLia-300x300.png",300,300,true],"cvmm-medium-plus":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/ShabatonMariapolisLia-305x207.png",305,207,true],"cvmm-portrait":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/ShabatonMariapolisLia-400x397.png",400,397,true],"cvmm-medium-square":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/ShabatonMariapolisLia.png",598,397,false],"cvmm-large":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/ShabatonMariapolisLia.png",598,397,false],"cvmm-small":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/ShabatonMariapolisLia-130x95.png",130,95,true],"full":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2024\/01\/ShabatonMariapolisLia.png",598,397,false]},"categories_names":{"60":{"name":"Di\u00e1logos en la Cultura","link":"https:\/\/www.focolaresciudadnueva.com\/inicio\/category\/dialogos-en-la-cultura\/"},"102":{"name":"Fraternidad","link":"https:\/\/www.focolaresciudadnueva.com\/inicio\/category\/fraternidad\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/posts\/6050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/comments?post=6050"}],"version-history":[{"count":1,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/posts\/6050\/revisions"}],"predecessor-version":[{"id":6055,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/posts\/6050\/revisions\/6055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/media\/6054"}],"wp:attachment":[{"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/media?parent=6050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/categories?post=6050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/tags?post=6050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}