{"id":4671,"date":"2023-11-16T08:00:00","date_gmt":"2023-11-16T12:00:00","guid":{"rendered":"https:\/\/www.focolaresciudadnueva.com\/?p=4671"},"modified":"2023-11-25T14:40:36","modified_gmt":"2023-11-25T18:40:36","slug":"vi-encuentro-mundial-de-scholas-occurrentes-y-world-ort-en-brasil","status":"publish","type":"post","link":"https:\/\/www.focolaresciudadnueva.com\/inicio\/vi-encuentro-mundial-de-scholas-occurrentes-y-world-ort-en-brasil\/","title":{"rendered":"VI Encuentro Mundial de Scholas Occurrentes y World ORT en Brasil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Fuente <a href=\"https:\/\/www.vaticannews.va\/es\">https:\/\/www.vaticannews.va\/es<\/a><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Este 26 de octubre, el Santo Padre ha enviado un video mensaje para la clausura del VI Encuentro Mundial de J\u00f3venes organizado por el Movimiento Educativo Internacional Scholas Occurrentes y World ORT, que se realiz\u00f3 del 23 al 26 de octubre en el Estado de San Pablo, en Brasil.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cUn encuentro para ser bien humano y no comercial que sea gratuito. Y para que haya encuentro debe haber movimiento\u201d, en esta frase el Papa Francisco resumi\u00f3 su mensaje a los j\u00f3venes participantes en el VI Encuentro Mundial de J\u00f3venes organizado por el Movimiento Educativo Internacional Scholas Occurrentes y World ORT, sobre el tema de la educaci\u00f3n como instrumento para el di\u00e1logo interreligioso y una cultura de paz, que se realiz\u00f3 del 23 al 26 de octubre en el Estado de San Pablo, en Brasil.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Movimiento, gratuidad y encuentro&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">A los 100 j\u00f3venes participantes en el Encuentro \u201cVida en movimiento\u201d, el Santo Padre en su video mensaje los anim\u00f3 a seguir trabajando, teniendo presente tres palabras claves: movimiento, gratuidad y encuentro.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cLes quiero agradecer a las autoridades de las ORT por el trabajo que est\u00e1n haciendo. Un trabajo de reflexi\u00f3n y adem\u00e1s de testimonio, con tres palabras claves: movimiento, gratuidad y encuentro.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAgradezco a las autoridades de las escuelas ORT que trabajan con Scholas, es una intuici\u00f3n que todav\u00eda no ha dado todo el alcance y eso que ya hace mucho. Es algo muy para el futuro, muy grande. Y agradecer tambi\u00e9n a las autoridades de Brasil que haya permitido o ayudado este tipo de cosas. Muchas gracias, que Dios los bendiga\u201d. (\u2026)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este 26 de octubre, el Santo Padre ha enviado un video mensaje para la clausura del VI Encuentro Mundial de J\u00f3venes organizado por el Movimiento Educativo Internacional Scholas Occurrentes y World ORT, que se realiz\u00f3 del 23 al 26 de octubre en el Estado de San Pablo, en Brasil. <a href=\"https:\/\/www.focolaresciudadnueva.com\/inicio\/vi-encuentro-mundial-de-scholas-occurrentes-y-world-ort-en-brasil\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">VI Encuentro Mundial de Scholas Occurrentes y World ORT en Brasil<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":4672,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[140,57,155],"tags":[],"class_list":["post-4671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-j4uw-jovenes-por-un-mundo-unido","category-jovenes","category-juventud-nueva"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2023\/11\/BrasilScholas1-150x150.png",150,150,true],"cvmm-medium":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2023\/11\/BrasilScholas1-300x300.png",300,300,true],"cvmm-medium-plus":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2023\/11\/BrasilScholas1-305x207.png",305,207,true],"cvmm-portrait":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2023\/11\/BrasilScholas1-400x485.png",400,485,true],"cvmm-medium-square":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2023\/11\/BrasilScholas1-600x485.png",600,485,true],"cvmm-large":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2023\/11\/BrasilScholas1.png",927,485,false],"cvmm-small":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2023\/11\/BrasilScholas1-130x95.png",130,95,true],"full":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2023\/11\/BrasilScholas1.png",927,485,false]},"categories_names":{"140":{"name":"J4UW - J\u00f3venes por un Mundo Unido","link":"https:\/\/www.focolaresciudadnueva.com\/inicio\/category\/dialogos-en-la-cultura\/j4uw-jovenes-por-un-mundo-unido\/"},"57":{"name":"J\u00f3venes","link":"https:\/\/www.focolaresciudadnueva.com\/inicio\/category\/jovenes\/"},"155":{"name":"Juventud Nueva","link":"https:\/\/www.focolaresciudadnueva.com\/inicio\/category\/juventud-nueva\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/posts\/4671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/comments?post=4671"}],"version-history":[{"count":2,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/posts\/4671\/revisions"}],"predecessor-version":[{"id":4674,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/posts\/4671\/revisions\/4674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/media\/4672"}],"wp:attachment":[{"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/media?parent=4671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/categories?post=4671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/tags?post=4671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}