{"id":18769,"date":"2025-07-14T08:00:00","date_gmt":"2025-07-14T12:00:00","guid":{"rendered":"https:\/\/www.focolaresciudadnueva.com\/inicio\/?p=18769"},"modified":"2025-07-16T09:23:07","modified_gmt":"2025-07-16T13:23:07","slug":"un-llamado-a-ser-los-primeros-en-cumplir-acuerdos-mppu-colombia","status":"publish","type":"post","link":"https:\/\/www.focolaresciudadnueva.com\/inicio\/un-llamado-a-ser-los-primeros-en-cumplir-acuerdos-mppu-colombia\/","title":{"rendered":"Un llamado a ser los primeros en cumplir acuerdos: MPPU Colombia"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><em>MPPU es el departamento pol\u00edtico de New Humanity, una ONG con estatus consultivo general.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.mppu.org\">www.mppu.org<\/a>&nbsp; | <a href=\"mailto:comisionmppucolombia@gmail.com\">comisionmppucolombia@gmail.com<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Como movimiento pol\u00edtico que busca el di\u00e1logo y construir la unidad en la diferencia, nos unimos al llamado que han hecho diferentes sectores de la sociedad a hacer un uso mesurado de la palabra, a practicar la no agresi\u00f3n en el debate pol\u00edtico, a utilizar un lenguaje que llame a la conciliaci\u00f3n y no a la divisi\u00f3n.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Nos unimos igualmente a la invitaci\u00f3n hecha por la Conferencia Episcopal Colombiana, y firmada por altas autoridades del gobierno el d\u00eda de ayer, lunes 16 de junio, donde textualmente, se nos llama, a todos los colombianos a \u00abescucharnos, valorarnos y respetarnos en hermandad; a desarmar y armonizar la palabra; y a rechazar todo tipo de violencia, como forma de resolver los conflictos pol\u00edticos y sociales\u00bb.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Queremos hacer un llamado enf\u00e1tico a la acci\u00f3n, a que los pactos firmados en estos d\u00edas sean una realidad, tanto en la calle, como en los medios, en los escenarios p\u00fablicos, que los pol\u00edticos de la democracia representativa sean ejemplo y garantes de cada una de las palabras de paz que promueven. Cumplamos los acuerdos, empecemos por cada uno, para demostrar que somos un pa\u00eds que cree en el di\u00e1logo, la reconciliaci\u00f3n y el respeto por la vida.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Entonces, pasemos de las palabras a los actos concretos. Por eso invitamos a todos y a todas, a generar di\u00e1logos vinculantes donde la humanidad prevalezca sobre las ideas, donde el respeto sea la palabra rectora y el ejercicio de escucha profunda el camino para comprender nuestras diferencias. Trabajemos juntos, con determinaci\u00f3n, por construir una Colombia con justicia social y paz, un pa\u00eds que se pone de acuerdo en lo elemental: la vida.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">En un mundo donde cada vida importa, la paz no es solo una meta lejana, es una responsabilidad diaria. Expresamos nuestra solidaridad con TODAS las v\u00edctimas que la violencia ha herido y con aquellas que ya se ha llevado.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><em>Comisi\u00f3n central del Movimiento Pol\u00edticos Por la Unidad &#8211; MPPU<\/em> <em>Colombia<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"540\" height=\"158\" src=\"https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2025\/07\/image-39.png\" alt=\"\" class=\"wp-image-18772\" srcset=\"https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2025\/07\/image-39.png 540w, https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2025\/07\/image-39-300x88.png 300w, https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2025\/07\/image-39-308x90.png 308w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Como movimiento pol\u00edtico que busca el di\u00e1logo y construir la unidad en la diferencia, nos unimos al llamado que han hecho diferentes sectores de la sociedad a hacer un uso mesurado de la palabra, a practicar la no agresi\u00f3n en el debate pol\u00edtico, a utilizar un lenguaje que llame a la conciliaci\u00f3n y no a la divisi\u00f3n. <a href=\"https:\/\/www.focolaresciudadnueva.com\/inicio\/un-llamado-a-ser-los-primeros-en-cumplir-acuerdos-mppu-colombia\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Un llamado a ser los primeros en cumplir acuerdos: MPPU Colombia<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":18771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,60,130],"tags":[],"class_list":["post-18769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colombia","category-dialogos-en-la-cultura","category-mppu-dialogos-en-la-cultura"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2025\/07\/COLOMBIA-MPPU-150x150.png",150,150,true],"cvmm-medium":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2025\/07\/COLOMBIA-MPPU-300x300.png",300,300,true],"cvmm-medium-plus":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2025\/07\/COLOMBIA-MPPU-305x207.png",305,207,true],"cvmm-portrait":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2025\/07\/COLOMBIA-MPPU-400x600.png",400,600,true],"cvmm-medium-square":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2025\/07\/COLOMBIA-MPPU-600x600.png",600,600,true],"cvmm-large":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2025\/07\/COLOMBIA-MPPU-1024x1000.png",1024,1000,true],"cvmm-small":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2025\/07\/COLOMBIA-MPPU-130x95.png",130,95,true],"full":["https:\/\/www.focolaresciudadnueva.com\/wp-content\/uploads\/2025\/07\/COLOMBIA-MPPU.png",2000,1000,false]},"categories_names":{"71":{"name":"Colombia","link":"https:\/\/www.focolaresciudadnueva.com\/inicio\/category\/colombia\/"},"60":{"name":"Di\u00e1logos en la Cultura","link":"https:\/\/www.focolaresciudadnueva.com\/inicio\/category\/dialogos-en-la-cultura\/"},"130":{"name":"MPPU","link":"https:\/\/www.focolaresciudadnueva.com\/inicio\/category\/dialogos-en-la-cultura\/mppu-dialogos-en-la-cultura\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/posts\/18769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/comments?post=18769"}],"version-history":[{"count":3,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/posts\/18769\/revisions"}],"predecessor-version":[{"id":18775,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/posts\/18769\/revisions\/18775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/media\/18771"}],"wp:attachment":[{"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/media?parent=18769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/categories?post=18769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolaresciudadnueva.com\/inicio\/wp-json\/wp\/v2\/tags?post=18769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}